{"id":10059,"date":"2024-02-04T10:00:48","date_gmt":"2024-02-04T09:00:48","guid":{"rendered":"https:\/\/www.suezo.it\/?p=10059"},"modified":"2024-02-04T11:18:53","modified_gmt":"2024-02-04T10:18:53","slug":"su-e-zo-per-la-terra-santa-il-progetto-di-solidarieta-2024","status":"publish","type":"post","link":"https:\/\/www.suezo.it\/en\/suezolive\/su-e-zo-per-la-terra-santa-il-progetto-di-solidarieta-2024","title":{"rendered":"(Italiano) Su e Zo per la Terra Santa: il progetto di solidarieta&#8217; 2024"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/www.suezo.it\/wp-content\/uploads\/2024\/02\/Post_Solidarieta_Suezo2024-01.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-10060\" src=\"https:\/\/i0.wp.com\/www.suezo.it\/wp-content\/uploads\/2024\/02\/Post_Solidarieta_Suezo2024-01.jpg?resize=300%2C300&#038;ssl=1\" alt=\"\" width=\"300\" height=\"300\" data-temp-aztec-id=\"c9f11bde-53a3-430b-bcf9-ba2d0bff0726\" srcset=\"https:\/\/i0.wp.com\/www.suezo.it\/wp-content\/uploads\/2024\/02\/Post_Solidarieta_Suezo2024-01.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.suezo.it\/wp-content\/uploads\/2024\/02\/Post_Solidarieta_Suezo2024-01.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.suezo.it\/wp-content\/uploads\/2024\/02\/Post_Solidarieta_Suezo2024-01.jpg?resize=255%2C255&amp;ssl=1 255w, https:\/\/i0.wp.com\/www.suezo.it\/wp-content\/uploads\/2024\/02\/Post_Solidarieta_Suezo2024-01.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.suezo.it\/wp-content\/uploads\/2024\/02\/Post_Solidarieta_Suezo2024-01.jpg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/www.suezo.it\/wp-content\/uploads\/2024\/02\/Post_Solidarieta_Suezo2024-01.jpg?resize=178%2C178&amp;ssl=1 178w, https:\/\/i0.wp.com\/www.suezo.it\/wp-content\/uploads\/2024\/02\/Post_Solidarieta_Suezo2024-01.jpg?w=1020&amp;ssl=1 1020w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Per l&#8217;annualit\u00e0 2024 il Consiglio Direttivo TGS Eurogroup ha deciso di destinare le somme che saranno raccolte per beneficenza nel corso dell&#8217;anno in occasione delle proprie iniziative di solidariet\u00e0, tra cui la Su e Zo per i Ponti, alle <strong>opere salesiane in Terra Santa<\/strong>.<\/p>\n<p>Dopo le missioni salesiane di Aleppo (sostenuta con le raccolte fondi del biennio 2014-2015) e Damasco (2016-2017) in Siria, dopo la missione salesiana di Iauaret\u00ea in Amazzonia, Brasile (2018-2019) e quella di Quebrada Honda, in Per\u00f9 (2022-2023), TGS Eurogroup torna a mettere al centro della propria opera di solidariet\u00e0 le realt\u00e0 salesiane del Medio Oriente, grazie al contatto diretto con Don Alejandro Le\u00f3n, Salesiano di Don Bosco, Ispettore Salesiano del Medio Oriente.<\/p>\n<p>I Salesiani di Don Bosco sono presenti in Medio Oriente da 130 anni con tutte le attivit\u00e0 tipiche della congregazione salesiana. All\u2019inizio con gli orfanotrofi, sia per i locali che per i migranti. Al giorno d\u2019oggi l\u2019azione si concentra su tre grandi settori di attivit\u00e0: il primo riguarda le scuole professionali e l\u2019educazione al lavoro; il secondo comprende gli oratori e i centri giovanili, alcuni sono solo per cristiani, altri per soli musulmani e altri ancora per entrambi; infine, negli ultimi 15 anni si svolge un\u2019intensa attivit\u00e0 nel campo dell\u2019assistenza ai rifugiati.<br \/>\nLa presenza salesiana in Terra Santa include comunit\u00e0 sia in territorio israeliano (Nazareth, Beitgemal, Gerusalemme) che in territorio palestinese (Betlemme, Cremisan).<br \/>\nA seguito dell&#8217;inasprimento della guerra in Medio Oriente, oggi pi\u00f9 che mai \u00e8 necessario sostenere le realt\u00e0 salesiane in Terra Santa che pi\u00f9 si adoperano per il sostegno delle comunit\u00e0 locali.<\/p>\n<p>Cos\u00ec lo stesso don Alejandro lancia un appello per la pace in Medio Oriente:<\/p>\n<blockquote><p>Voglio ringraziare di cuore tutti gli amici della Famiglia Salesiana e i giovani del Movimento Giovanile Salesiano soprattutto per la vostra preghiera. La nostra \u00e8 una situazione di tensione ma vi sentiamo vicini: affidiamoci a Don Bosco e a Maria Ausiliatrice perch\u00e9 possa arrivare presto la pace<\/p><\/blockquote>\n<p style=\"text-align:right;\"><em>Don Alejandro Le\u00f3n, SDB<\/em><br \/>\n<em>Ispettore Salesiano del Medio Oriente<\/em><\/p>\n<p><!--more--><\/p>\n<div><strong>Per sostenere le opere salesiane in Terra Santa<\/strong><br \/>\nE\u2019 possibile effettuare donazioni dirette a favore delle opere salesiane in Terra Santa tramite bonifico bancario sul seguente conto corrente:<\/p>\n<p>Beneficiario: Direzione Generale Opere Don Bosco<br \/>\nVia Marsala 42<br \/>\n00185 Roma<\/p>\n<p>Banca: Banca Popolare di Sondrio<br \/>\nAGENZIA N. 2 &#8211; ROMA<br \/>\nVia Gherardi Silvestro 45<br \/>\n00146 Roma<\/p>\n<p>IBAN: IT54O0569603202000004655X77<br \/>\nBIC\/SWIFT: POSOIT22<\/p>\n<p>Causale: &#8220;Su e Zo per i Ponti per la Terra Santa&#8221;\n<\/p><\/div>\n<div align=\"JUSTIFY\"><em>Lo Staff della Su e Zo<\/em><\/p>\n<div class=\"single-post-download\">\n<div class=\"boxed\">\n<h2>Link correlati<\/h2>\n<div class=\"single-post-related-entries\">\n<ul>\n<li><a href=\"https:\/\/donboscomor.org\/?lang=it\">Sito web dell&#8217;Ispettoria Salesiana del Medio Oriente<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Per l&#8217;annualit\u00e0 2024 il Consiglio Direttivo TGS Eurogroup ha deciso di destinare le somme che saranno raccolte per beneficenza nel corso dell&#8217;anno in occasione delle proprie iniziative di solidariet\u00e0, tra cui la Su e Zo per i Ponti, alle opere &hellip; <a href=\"https:\/\/www.suezo.it\/en\/suezolive\/su-e-zo-per-la-terra-santa-il-progetto-di-solidarieta-2024\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":10060,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[138,23,5],"tags":[15,20,499],"class_list":["post-10059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-salesiani","category-su-e-zo-per-i-ponti","tag-beneficenza","tag-missione-salesiana","tag-terra-santa"],"jetpack_publicize_connections":[],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.suezo.it\/wp-content\/uploads\/2024\/02\/Post_Solidarieta_Suezo2024-01.jpg?fit=1020%2C1020&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p50lBT-2Cf","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suezo.it\/en\/wp-json\/wp\/v2\/posts\/10059"}],"collection":[{"href":"https:\/\/www.suezo.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suezo.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suezo.it\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suezo.it\/en\/wp-json\/wp\/v2\/comments?post=10059"}],"version-history":[{"count":6,"href":"https:\/\/www.suezo.it\/en\/wp-json\/wp\/v2\/posts\/10059\/revisions"}],"predecessor-version":[{"id":10066,"href":"https:\/\/www.suezo.it\/en\/wp-json\/wp\/v2\/posts\/10059\/revisions\/10066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suezo.it\/en\/wp-json\/wp\/v2\/media\/10060"}],"wp:attachment":[{"href":"https:\/\/www.suezo.it\/en\/wp-json\/wp\/v2\/media?parent=10059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suezo.it\/en\/wp-json\/wp\/v2\/categories?post=10059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suezo.it\/en\/wp-json\/wp\/v2\/tags?post=10059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}